{"id":17776,"date":"2018-09-11T19:00:10","date_gmt":"2018-09-11T19:00:10","guid":{"rendered":"https:\/\/cocina-casera.com\/mx\/?p=17776"},"modified":"2018-09-17T18:04:13","modified_gmt":"2018-09-17T18:04:13","slug":"cantarito-de-tequila-receta-mexicana-facil","status":"publish","type":"post","link":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/","title":{"rendered":"Cantarito de tequila. Receta mexicana f\u00e1cil"},"content":{"rendered":"<div class='valores'><div class='valor'>20 m<\/div><div class='valor'>Calorias: 96<\/div><div class='valor'>F\u00e1cil<\/div><div class='valor'>1 persona<\/div><\/div><p>El tequila, bebida hecha de agave con denominaci\u00f3n de origen en M\u00e9xico, est\u00e1 conquistando el mundo. Aunque usualmente suele tomarse solo, con sal y lim\u00f3n, en Jalisco est\u00e1n innovando la manera de servirlo. Por ejemplo, el <strong>cantarito de tequila<\/strong>. Esta bebida se puede acompa\u00f1ar perfecto de cualquier <a href=\"https:\/\/cocina-casera.com\/mx\/\">comida mexicana<\/a>, aunque es usual tomarlo solo.\u00a0Esta bebida se ha vuelto muy popular, gracias a las redes sociales cantaros grandes, de m\u00e1s de un litro. Conocidos tambi\u00e9n como cantaros locos.<\/p>\n<p>La idea de preparar un famoso y refrescante <strong>cantarito de tequila<\/strong> es que podemos disfrutar de una bebida con alcohol de una manera diferente. El sabor del tequila se mezcla perfecto con las frutas brindando toda una experiencia en nuestro paladar. El motivo de usar frutas c\u00edtricas es para que apreciemos mejor las notas de sabor del tequila.<\/p>\n<p>El cantarito es un tarro hecho de barro por manos artesanas mexicanas. Anteriormente, en las rancher\u00edas o pueblos, se acostumbra ir por agua para tomar a los r\u00edos, dicha agua era tra\u00edda y almacenada en jarrones, cantaros o tinaja, permaneciendo siempre fresca.<\/p>\n<p>Aunque de las <a href=\"https:\/\/cocina-casera.com\/mx\/recetas-de-bebidas-mexicanas\/\">recetas de bebidas mexicanas<\/a> preparadas con tequila, la m\u00e1s famosa son las margaritas. De las cuales tambi\u00e9n ya hay de sabores, como las <a href=\"https:\/\/cocina-casera.com\/mx\/margarita-fresa-receta-mexicana\/\">margaritas de fresas<\/a>.<\/p>\n<h2 class=\"p-20-t\">Ingredientes para Cantarito de tequila. Receta mexicana f\u00e1cil para 1 persona<\/h2><ul><li>Sal - al gusto<\/li><li>Hielo - al gusto<\/li><li>Tequila - 1 y 1\/2 oz<\/li><li>Jugo de lim\u00f3n - 1 pieza de lim\u00f3n<\/li><li>Jugo de naranja - 2 cucharadas<\/li><li>Jugo de toronja - 2 cucharadas<\/li><li>Refresco de lim\u00f3n - al gusto<\/li><li>Gajos de fruta con c\u00e1scara lim\u00f3n, naranja y toronja - al gusto<\/li><\/ul><h2>C\u00f3mo hacer la receta de Cantarito de tequila. Receta mexicana f\u00e1cil<\/h2><ol id='lista4'><li>Escarchamos con sal un cantarito o tarro de barro y llevamos al congelador por 10 minutos.<\/li><li>Cuando retiremos nuestro cantarito, a\u00f1adimos el hielo, los jugos de frutas, el refresco y el tequila. Revolvemos todo muy bien.<\/li><li>Colocamos los gajos de frutas en nuestro cantarito de tequila y disfrutamos.<\/li><\/ol><h2>Notas y Consejos<\/h2><p>Lo ideal es que usemos el jugo de frutas reci\u00e9n hecho, eso le a\u00f1adir\u00eda un sabor peculiar a nuestro <strong>cantarito de tequila<\/strong>.<\/p>\n<p>En caso de que no tengamos cantaritos, podemos usar jarrones de barro o alg\u00fan otro traste hecho con este material. Si carecemos de eso, podemos usar tazas de peltre, cobre o aluminio. Aunque un vaso tambi\u00e9n nos puede funcionar perfecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.<\/p>\n","protected":false},"author":3,"featured_media":17788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-17776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas-de-bebidas-mexicanas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cantarito de tequila. Receta mexicana f\u00e1cil<\/title>\n<meta name=\"description\" content=\"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cantarito de tequila. Receta mexicana f\u00e1cil\" \/>\n<meta property=\"og:description\" content=\"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/\" \/>\n<meta property=\"og:site_name\" content=\"Recetas de Comida Mexicana\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-11T19:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-17T18:04:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jose Balandin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jose Balandin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/\",\"url\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/\",\"name\":\"Cantarito de tequila. Receta mexicana f\u00e1cil\",\"isPartOf\":{\"@id\":\"https:\/\/cocina-casera.com\/mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg\",\"datePublished\":\"2018-09-11T19:00:10+00:00\",\"dateModified\":\"2018-09-17T18:04:13+00:00\",\"author\":{\"@id\":\"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/0470f74be6c221c1aea6680c007ad2c8\"},\"description\":\"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.\",\"breadcrumb\":{\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage\",\"url\":\"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg\",\"contentUrl\":\"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg\",\"width\":700,\"height\":470,\"caption\":\"Cantarito de tequila. Receta mexicana f\u00e1cil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cocina-casera.com\/mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cantarito de tequila. Receta mexicana f\u00e1cil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/#website\",\"url\":\"https:\/\/cocina-casera.com\/mx\/\",\"name\":\"Recetas de Comida Mexicana\",\"description\":\"Las mejores comidas mexicanas. Recetas de M\u00e9xico f\u00e1ciles y caseras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cocina-casera.com\/mx\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/0470f74be6c221c1aea6680c007ad2c8\",\"name\":\"Jose Balandin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0bb3ec5dcc6bab076b7f090dcd454514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0bb3ec5dcc6bab076b7f090dcd454514?s=96&d=mm&r=g\",\"caption\":\"Jose Balandin\"},\"description\":\"Soy un apasionado de la creaci\u00f3n de contenido y ya hace m\u00e1s de 10 a\u00f1os que fund\u00e9 Cocina Casera. En este tiempo hemos conseguido ser unas de las webs m\u00e1s le\u00eddas del mundo en gastronom\u00eda enfoc\u00e1ndonos en el contenido de alta calidad y creado m\u00e1s de 1.1.000 v\u00eddeo recetas. He fundado otros proyectos como Instituto Emprende. Puedes ver todos mis proyectos y redes sociales mi web personal\",\"sameAs\":[\"https:\/\/josebalandin.com\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cantarito de tequila. Receta mexicana f\u00e1cil","description":"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/","og_locale":"es_ES","og_type":"article","og_title":"Cantarito de tequila. Receta mexicana f\u00e1cil","og_description":"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.","og_url":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/","og_site_name":"Recetas de Comida Mexicana","article_published_time":"2018-09-11T19:00:10+00:00","article_modified_time":"2018-09-17T18:04:13+00:00","og_image":[{"width":700,"height":470,"url":"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg","type":"image\/jpeg"}],"author":"Jose Balandin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jose Balandin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/","url":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/","name":"Cantarito de tequila. Receta mexicana f\u00e1cil","isPartOf":{"@id":"https:\/\/cocina-casera.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage"},"image":{"@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage"},"thumbnailUrl":"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg","datePublished":"2018-09-11T19:00:10+00:00","dateModified":"2018-09-17T18:04:13+00:00","author":{"@id":"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/0470f74be6c221c1aea6680c007ad2c8"},"description":"El cantarito de tequila, naci\u00f3 en Jalisco, sede del tequila en M\u00e9xico y se ha vuelto muy popular por su presentaci\u00f3n y refrescante sabor.","breadcrumb":{"@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#primaryimage","url":"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg","contentUrl":"https:\/\/cocina-casera.com\/mx\/wp-content\/uploads\/2018\/09\/cantarito.jpg","width":700,"height":470,"caption":"Cantarito de tequila. Receta mexicana f\u00e1cil"},{"@type":"BreadcrumbList","@id":"https:\/\/cocina-casera.com\/mx\/cantarito-de-tequila-receta-mexicana-facil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cocina-casera.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Cantarito de tequila. Receta mexicana f\u00e1cil"}]},{"@type":"WebSite","@id":"https:\/\/cocina-casera.com\/mx\/#website","url":"https:\/\/cocina-casera.com\/mx\/","name":"Recetas de Comida Mexicana","description":"Las mejores comidas mexicanas. Recetas de M\u00e9xico f\u00e1ciles y caseras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cocina-casera.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/0470f74be6c221c1aea6680c007ad2c8","name":"Jose Balandin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cocina-casera.com\/mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0bb3ec5dcc6bab076b7f090dcd454514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0bb3ec5dcc6bab076b7f090dcd454514?s=96&d=mm&r=g","caption":"Jose Balandin"},"description":"Soy un apasionado de la creaci\u00f3n de contenido y ya hace m\u00e1s de 10 a\u00f1os que fund\u00e9 Cocina Casera. En este tiempo hemos conseguido ser unas de las webs m\u00e1s le\u00eddas del mundo en gastronom\u00eda enfoc\u00e1ndonos en el contenido de alta calidad y creado m\u00e1s de 1.1.000 v\u00eddeo recetas. He fundado otros proyectos como Instituto Emprende. Puedes ver todos mis proyectos y redes sociales mi web personal","sameAs":["https:\/\/josebalandin.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/posts\/17776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/comments?post=17776"}],"version-history":[{"count":0,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/posts\/17776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/media\/17788"}],"wp:attachment":[{"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/media?parent=17776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/categories?post=17776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocina-casera.com\/mx\/wp-json\/wp\/v2\/tags?post=17776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}